{"id":22969,"date":"2026-04-22T15:37:05","date_gmt":"2026-04-22T15:37:05","guid":{"rendered":"https:\/\/wearecapco.com\/news\/le-skymaze-reimagine\/"},"modified":"2026-04-22T15:37:05","modified_gmt":"2026-04-22T15:37:05","slug":"le-skymaze-reimagine","status":"publish","type":"news","link":"https:\/\/wearecapco.com\/fr\/news\/le-skymaze-reimagine\/","title":{"rendered":"Le Skymaze r\u00e9imagin\u00e9"},"content":{"rendered":"<h3 style=\"text-align: left;\">Un nouveau chapitre pour un vieil ami<\/h3>\n<p style=\"text-align: left;\">Dans le domaine du fabuleux parc faunique et jardins des Cotswolds, le c\u00e9l\u00e8bre terrain de jeux d\u2019aventure \u00ab Skymaze \u00bb du parc est depuis longtemps une destination de jeux d\u2019aventure, d\u2019exploration et de cr\u00e9ation de souvenirs pour les familles. Apr\u00e8s plus d\u2019une d\u00e9cennie d\u2019utilisation constante et environ 4,5 millions de visiteurs, ce terrain de jeu tant appr\u00e9ci\u00e9 a \u00e9t\u00e9 r\u00e9imagin\u00e9 et reconstruit pour une nouvelle g\u00e9n\u00e9ration. <\/p>\n<p style=\"text-align: left;\">Les travaux ont commenc\u00e9 avec l\u2019\u00e9quipe CAP.CO qui a d\u00e9mont\u00e9 toute la structure. Tous les travaux en acier inoxydable pour les toboggans, les poteaux et certains \u00e9l\u00e9ments d\u2019escalade ont \u00e9t\u00e9 r\u00e9nov\u00e9s pr\u00eats \u00e0 \u00eatre r\u00e9utilis\u00e9s, et la construction achev\u00e9e en un temps record, pr\u00eate \u00e0 rouvrir pendant le jour f\u00e9ri\u00e9 de P\u00e2ques, et pour accueillir la 56e ann\u00e9e du parc. <\/p>\n<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-22965\" src=\"https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/SKYMAZE-ORIGINAL-BEING-DISMANTLED-then-Created-by-CAP.CO_.jpg\" alt=\"SKYMAZE ORIGINAL D\u00c9MANTEL\u00c9 - puis cr\u00e9\u00e9 par CAP.CO\" width=\"1920\" height=\"1440\" srcset=\"https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/SKYMAZE-ORIGINAL-BEING-DISMANTLED-then-Created-by-CAP.CO_.jpg 1920w, https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/SKYMAZE-ORIGINAL-BEING-DISMANTLED-then-Created-by-CAP.CO_-300x225.jpg 300w, https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/SKYMAZE-ORIGINAL-BEING-DISMANTLED-then-Created-by-CAP.CO_-768x576.jpg 768w, https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/SKYMAZE-ORIGINAL-BEING-DISMANTLED-then-Created-by-CAP.CO_-1536x1152.jpg 1536w, https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/SKYMAZE-ORIGINAL-BEING-DISMANTLED-then-Created-by-CAP.CO_-533x400.jpg 533w, https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/SKYMAZE-ORIGINAL-BEING-DISMANTLED-then-Created-by-CAP.CO_-400x300.jpg 400w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/p>\n<h3 style=\"text-align: left;\">Un terrain de jeu ancr\u00e9 sur place<\/h3>\n<p style=\"text-align: left;\">Le nouveau Skymaze s\u2019\u00e9l\u00e8ve \u00e0 travers trois niveaux de cabanes dans les arbres interconnect\u00e9es, de passerelles et de parcours de jeu \u2014 une structure en couches qui invite les enfants \u00e0 bouger, explorer et d\u00e9couvrir. Des ponts de corde s\u2019\u00e9tendent entre les tours, des tunnels rampants testent les nerfs et les genoux, et les toboggans en acier inoxydable acc\u00e9l\u00e8rent en toute s\u00e9curit\u00e9 les explorateurs jusqu\u2019au niveau du sol, avant leur prochaine ascension. <\/p>\n<p style=\"text-align: left;\">C\u2019est d\u00e9lib\u00e9r\u00e9ment intuitif. Pas de chemin fixe. Aucun r\u00e9sultat prescrit. Juste la libert\u00e9 d\u2019explorer.   <\/p>\n<h3 style=\"text-align: left;\">Con\u00e7u pour la long\u00e9vit\u00e9, con\u00e7u pour \u00eatre utilis\u00e9<\/h3>\n<p style=\"text-align: left;\">Le Skymaze original a r\u00e9ussi car il a \u00e9t\u00e9 utilis\u00e9 de fa\u00e7on intensive, joyeuse et sans pause. Son successeur a \u00e9t\u00e9 con\u00e7u avec cette m\u00eame intensit\u00e9 en t\u00eate. <\/p>\n<p style=\"text-align: left;\">Une palette encore plus robuste de mat\u00e9riaux, dont le bois de Robinia, constitue l\u2019\u00e9pine dorsale de la structure. Dense, r\u00e9siliente et naturellement durable, il permet au terrain de jeu de r\u00e9sister \u00e0 la fois au temps et \u00e0 l\u2019utilisation avec un minimum d\u2019intervention. Plus de 120 poteaux structurels ancrent le sch\u00e9ma, supportant plus de 600 \u00e9l\u00e9ments en bois individuels \u2014 chacun faisant partie de l\u2019environnement de jeu plus vaste et coh\u00e9rent.  <\/p>\n<h3 style=\"text-align: left;\">Con\u00e7u par la collaboration<\/h3>\n<p style=\"text-align: left;\">La reconstruction a \u00e9t\u00e9 fa\u00e7onn\u00e9e gr\u00e2ce \u00e0 une relation de travail \u00e9troite entre CAP.CO, l\u2019\u00e9quipe des terrains du parc et les conseils de RoSPA.<\/p>\n<p style=\"text-align: left;\">Ensemble, le cahier des charges \u00e9tait clair : conserver l\u2019esprit de l\u2019original, tout en cr\u00e9ant quelque chose qui perdurerait \u2013 structurellement, op\u00e9rationnellement et exp\u00e9rimentalement.<\/p>\n<p style=\"text-align: left;\">La construction a eu lieu pendant les mois d\u2019hiver, permettant au terrain de jeu de revenir \u00e0 temps pour le printemps \u2014 pr\u00eat pour les saisons qui comptent le plus pour toute attraction de plein air au Royaume-Uni.<\/p>\n<h3 style=\"text-align: left;\">Longue dur\u00e9e de la continuit\u00e9<\/h3>\n<p style=\"text-align: left;\">Skymaze a toujours fait partie d\u2019une culture plus large de jeu au sein du parc \u2014 une lign\u00e9e qui remonte \u00e0 ses d\u00e9buts, des simples toboggans aux structures artisanales qui captivaient l\u2019imagination \u2014 le c\u00e9l\u00e8bre cheval de Troie d\u2019autrefois est un souvenir qui reste longtemps dans la m\u00e9moire.<\/p>\n<p style=\"text-align: left;\">\u00c0 c\u00f4t\u00e9 de la structure principale, les plus jeunes visiteurs peuvent explorer le Mini-Manoir du parc \u2013 un environnement \u00e0 grande \u00e9chelle compos\u00e9 de plateformes, de toboggans et d\u2019une tyrolienne miniature con\u00e7ue pour les jeux de la petite enfance. Ailleurs, des \u00e9l\u00e9ments de longue date comme le lieu original de la balan\u00e7oire continuent d\u2019ancrer la m\u00e9moire et la familiarit\u00e9 dans le paysage. <\/p>\n<p style=\"text-align: left;\">\u00c0 son point le plus \u00e9lev\u00e9, le nouveau Skymaze s\u2019ouvre sur une plateforme d\u2019observation situ\u00e9e \u00e0 pr\u00e8s de huit m\u00e8tres du sol \u2014 offrant un moment de pause, de perspective et de connexion avec le parc plus large.<\/p>\n<h3 style=\"text-align: left;\">Viens t\u2019\u00e9merveiller<\/h3>\n<p style=\"text-align: left;\">Le Skymaze se trouve dans le parc faunique des Cotswolds \u00e0 Burford, dans l\u2019Oxfordshire, et est ouvert tous les jours. Les meilleurs prix pour les billets sont toujours en ligne \u00e0 l\u2019avance. C\u2019est l\u2019une des plus grandes collections zoologiques du Royaume-Uni et cela vaut vraiment le d\u00e9tour.    <a href=\"https:\/\/www.cotswoldwildlifepark.co.uk\/\" target=\"_blank\" rel=\"noopener\">Vous pouvez le voir ici.<\/a><\/p>\n<p style=\"text-align: left;\">Voici quelques photos \u00e0 son ouverture.<\/p>\n<p style=\"text-align: left;\"><div  id=\"jtg-22968\" class=\"modula modula-gallery modula-custom-grid\" data-config=\"{&quot;height&quot;:800,&quot;tabletHeight&quot;:800,&quot;mobileHeight&quot;:800,&quot;desktopHeight&quot;:800,&quot;enableTwitter&quot;:false,&quot;enableWhatsapp&quot;:false,&quot;enableFacebook&quot;:false,&quot;enablePinterest&quot;:false,&quot;enableLinkedin&quot;:false,&quot;enableEmail&quot;:false,&quot;randomFactor&quot;:0.5,&quot;type&quot;:&quot;custom-grid&quot;,&quot;columns&quot;:12,&quot;gutter&quot;:5,&quot;mobileGutter&quot;:5,&quot;tabletGutter&quot;:5,&quot;desktopGutter&quot;:5,&quot;enableResponsive&quot;:true,&quot;tabletColumns&quot;:2,&quot;mobileColumns&quot;:1,&quot;lazyLoad&quot;:0,&quot;lightboxOpts&quot;:{&quot;animated&quot;:true,&quot;Thumbs&quot;:{&quot;type&quot;:&quot;modern&quot;,&quot;showOnStart&quot;:false},&quot;Toolbar&quot;:{&quot;display&quot;:{&quot;right&quot;:[&quot;close&quot;]},&quot;enabled&quot;:true},&quot;Carousel&quot;:{&quot;Panzoom&quot;:{&quot;touch&quot;:true},&quot;infinite&quot;:false},&quot;keyboard&quot;:{&quot;Escape&quot;:&quot;close&quot;,&quot;Delete&quot;:&quot;close&quot;,&quot;Backspace&quot;:&quot;close&quot;,&quot;PageUp&quot;:&quot;next&quot;,&quot;PageDown&quot;:&quot;prev&quot;,&quot;ArrowUp&quot;:&quot;prev&quot;,&quot;ArrowDown&quot;:&quot;next&quot;,&quot;ArrowRight&quot;:&quot;next&quot;,&quot;ArrowLeft&quot;:&quot;prev&quot;},&quot;wheel&quot;:&quot;slide&quot;,&quot;touch&quot;:true,&quot;backdropClick&quot;:&quot;close&quot;,&quot;l10n&quot;:{&quot;CLOSE&quot;:&quot;Close&quot;,&quot;NEXT&quot;:&quot;Next&quot;,&quot;PREV&quot;:&quot;Previous&quot;,&quot;Error&quot;:&quot;The requested content cannot be loaded. Please try again later.&quot;,&quot;PLAY_START&quot;:&quot;Start slideshow&quot;,&quot;PLAY_STOP&quot;:&quot;Pause slideshow&quot;,&quot;FULL_SCREEN&quot;:&quot;Full screen&quot;,&quot;THUMBS&quot;:&quot;Thumbnails&quot;,&quot;DOWNLOAD&quot;:&quot;Download&quot;,&quot;SHARE&quot;:&quot;Share&quot;,&quot;ZOOM&quot;:&quot;Zoom&quot;,&quot;EMAIL&quot;:&quot;Here is the link to the image : %%image_link%% and this is the link to the gallery : %%gallery_link%%&quot;,&quot;MODAL&quot;:&quot;You can close this modal content with the ESC key&quot;,&quot;ERROR&quot;:&quot;Something Went Wrong, Please Try Again Later&quot;,&quot;IMAGE_ERROR&quot;:&quot;Image Not Found&quot;,&quot;ELEMENT_NOT_FOUND&quot;:&quot;HTML Element Not Found&quot;,&quot;AJAX_NOT_FOUND&quot;:&quot;Error Loading AJAX : Not Found&quot;,&quot;AJAX_FORBIDDEN&quot;:&quot;Error Loading AJAX : Forbidden&quot;,&quot;IFRAME_ERROR&quot;:&quot;Error Loading Page&quot;,&quot;TOGGLE_ZOOM&quot;:&quot;Toggle zoom level&quot;,&quot;TOGGLE_THUMBS&quot;:&quot;Toggle thumbnails&quot;,&quot;TOGGLE_SLIDESHOW&quot;:&quot;Toggle slideshow&quot;,&quot;TOGGLE_FULLSCREEN&quot;:&quot;Toggle full-screen mode&quot;},&quot;Images&quot;:{&quot;Panzoom&quot;:{&quot;maxScale&quot;:2}},&quot;mainClass&quot;:&quot;modula-fancybox-container modula-lightbox-jtg-22968&quot;,&quot;Html&quot;:{&quot;videoAutoplay&quot;:0,&quot;videoTpl&quot;:&quot;&lt;video class=\\&quot;fancybox__html5video\\&quot; controls muted playsinline controlsList controlsList=\\&quot;nodownload\\&quot; poster=\\&quot;{{poster}}\\&quot; src=\\&quot;{{src}}\\&quot; type=\\&quot;{{format}}\\&quot; &gt;  Sorry, your browser doesn&#039;t support embedded videos, &lt;a href=\\&quot;{{src}}\\&quot;&gt; download &lt;\\\/a&gt; and watch with your favorite video player! &lt;\\\/video&gt;&quot;}},&quot;inView&quot;:false,&quot;email_subject&quot;:&quot;Check out this awesome image !!&quot;,&quot;email_message&quot;:&quot;Here is the link to the image : %%image_link%% and this is the link to the gallery : %%gallery_link%%&quot;,&quot;lightbox&quot;:&quot;fancybox&quot;,&quot;lightbox_devices&quot;:&quot;both&quot;}\">\n\n\t\n\t<div  class=\"modula-items\">\n\t\t<div class=\"modula-item effect-pufrobo\" data-width=\"4\" data-height=\"3\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"22978\" role=\"button\" tabindex=\"0\" rel=\"jtg-22968\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-22978\"  data-valign=\"middle\" data-halign=\"center\" alt=\"Henry and Mollie Skymaze Created by CAP.CO\" data-full=\"https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-Skymaze-Created-by-CAP.CO_.jpg\" title=\"Henry and Mollie Skymaze Created by CAP.CO\" crop=\"\" width=\"1920\" height=\"1280\" src=\"https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-Skymaze-Created-by-CAP.CO_.jpg\" data-src=\"https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-Skymaze-Created-by-CAP.CO_.jpg\" data-caption=\"\" srcset=\"https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-Skymaze-Created-by-CAP.CO_.jpg 1920w, https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-Skymaze-Created-by-CAP.CO_-300x200.jpg 300w, https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-Skymaze-Created-by-CAP.CO_-768x512.jpg 768w, https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-Skymaze-Created-by-CAP.CO_-1536x1024.jpg 1536w, https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-Skymaze-Created-by-CAP.CO_-600x400.jpg 600w, https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-Skymaze-Created-by-CAP.CO_-450x300.jpg 450w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" data-width=\"4\" data-height=\"3\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"22975\" role=\"button\" tabindex=\"0\" rel=\"jtg-22968\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-22975\"  data-valign=\"middle\" data-halign=\"center\" alt=\"Henry and Mollie Skymaze 2 Created by CAP.CO\" data-full=\"https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-Skymaze-2-Created-by-CAP.CO_.jpg\" title=\"Henry and Mollie Skymaze 2 Created by CAP.CO\" crop=\"\" width=\"1920\" height=\"1280\" src=\"https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-Skymaze-2-Created-by-CAP.CO_.jpg\" data-src=\"https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-Skymaze-2-Created-by-CAP.CO_.jpg\" data-caption=\"\" srcset=\"https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-Skymaze-2-Created-by-CAP.CO_.jpg 1920w, https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-Skymaze-2-Created-by-CAP.CO_-300x200.jpg 300w, https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-Skymaze-2-Created-by-CAP.CO_-768x512.jpg 768w, https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-Skymaze-2-Created-by-CAP.CO_-1536x1024.jpg 1536w, https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-Skymaze-2-Created-by-CAP.CO_-600x400.jpg 600w, https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-Skymaze-2-Created-by-CAP.CO_-450x300.jpg 450w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" data-width=\"4\" data-height=\"3\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"22972\" role=\"button\" tabindex=\"0\" rel=\"jtg-22968\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-22972\"  data-valign=\"middle\" data-halign=\"center\" alt=\"Henry and Mollie on Skymaze Created by CAP.CO\" data-full=\"https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-on-Skymaze-Created-by-CAP.CO_.jpg\" title=\"Henry and Mollie on Skymaze Created by CAP.CO\" crop=\"\" width=\"1920\" height=\"1280\" src=\"https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-on-Skymaze-Created-by-CAP.CO_.jpg\" data-src=\"https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-on-Skymaze-Created-by-CAP.CO_.jpg\" data-caption=\"\" srcset=\"https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-on-Skymaze-Created-by-CAP.CO_.jpg 1920w, https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-on-Skymaze-Created-by-CAP.CO_-300x200.jpg 300w, https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-on-Skymaze-Created-by-CAP.CO_-768x512.jpg 768w, https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-on-Skymaze-Created-by-CAP.CO_-1536x1024.jpg 1536w, https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-on-Skymaze-Created-by-CAP.CO_-600x400.jpg 600w, https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Mollie-on-Skymaze-Created-by-CAP.CO_-450x300.jpg 450w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\t\t\n\t<\/div>\n\n\t\n\t\n\t<script type=\"application\/ld+json\">\n\t{\n\t\t\"@context\": \"https:\/\/schema.org\",\n\t\t\"@type\"   : \"ImageGallery\",\n\t\t\"id\"      : \"https:\/\/wearecapco.com\/fr\/news\/le-skymaze-reimagine\/#modula-gallery-22968\",\n\t\t\"url\"     : \"https:\/\/wearecapco.com\/fr\/news\/le-skymaze-reimagine\/\"\n\t}\n\n\t<\/script>\n\n\t\n<\/div>\n<\/p>\n","protected":false},"featured_media":22964,"template":"","categories":[31,28],"class_list":["post-22969","news","type-news","status-publish","has-post-thumbnail","hentry","category-attractions-fr","category-jeu-daventure"],"acf":{"text_under_title":"Burford, Royaume-Uni"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le Skymaze r\u00e9imagin\u00e9 | Parc faunique des Cotswold | CAP.CO<\/title>\n<meta name=\"description\" content=\"Apr\u00e8s plus d\u2019une d\u00e9cennie d\u2019utilisation constante et 4,5 millions de visiteurs, le Skymaze au CWP a \u00e9t\u00e9 r\u00e9imagin\u00e9 et reconstruit pour une nouvelle g\u00e9n\u00e9ration.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wearecapco.com\/fr\/news\/le-skymaze-reimagine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Skymaze r\u00e9imagin\u00e9 | Parc faunique des Cotswold | CAP.CO\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s plus d\u2019une d\u00e9cennie d\u2019utilisation constante et 4,5 millions de visiteurs, le Skymaze au CWP a \u00e9t\u00e9 r\u00e9imagin\u00e9 et reconstruit pour une nouvelle g\u00e9n\u00e9ration.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wearecapco.com\/fr\/news\/le-skymaze-reimagine\/\" \/>\n<meta property=\"og:site_name\" content=\"CAP.CO | Creating Adventurous Places Ltd.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wearecapco\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Molly-Skymaze-lead-image-Created-by-CAP.CO_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wearecapco.com\\\/fr\\\/news\\\/le-skymaze-reimagine\\\/\",\"url\":\"https:\\\/\\\/wearecapco.com\\\/fr\\\/news\\\/le-skymaze-reimagine\\\/\",\"name\":\"Le Skymaze r\u00e9imagin\u00e9 | Parc faunique des Cotswold | CAP.CO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wearecapco.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wearecapco.com\\\/fr\\\/news\\\/le-skymaze-reimagine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wearecapco.com\\\/fr\\\/news\\\/le-skymaze-reimagine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wearecapco.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Henry-and-Molly-Skymaze-lead-image-Created-by-CAP.CO_.jpg\",\"datePublished\":\"2026-04-22T15:37:05+00:00\",\"description\":\"Apr\u00e8s plus d\u2019une d\u00e9cennie d\u2019utilisation constante et 4,5 millions de visiteurs, le Skymaze au CWP a \u00e9t\u00e9 r\u00e9imagin\u00e9 et reconstruit pour une nouvelle g\u00e9n\u00e9ration.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wearecapco.com\\\/fr\\\/news\\\/le-skymaze-reimagine\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wearecapco.com\\\/fr\\\/news\\\/le-skymaze-reimagine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wearecapco.com\\\/fr\\\/news\\\/le-skymaze-reimagine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wearecapco.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Henry-and-Molly-Skymaze-lead-image-Created-by-CAP.CO_.jpg\",\"contentUrl\":\"https:\\\/\\\/wearecapco.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Henry-and-Molly-Skymaze-lead-image-Created-by-CAP.CO_.jpg\",\"width\":1536,\"height\":1024,\"caption\":\"Henry and Molly Skymaze lead image - Created by CAP.CO\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wearecapco.com\\\/fr\\\/news\\\/le-skymaze-reimagine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wearecapco.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualit\u00e9s\",\"item\":\"https:\\\/\\\/wearecapco.com\\\/fr\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le Skymaze r\u00e9imagin\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wearecapco.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/wearecapco.com\\\/fr\\\/\",\"name\":\"CAP.CO | Creating Adventurous Places Ltd.\",\"description\":\"Creating adventurous places for every imagination\",\"publisher\":{\"@id\":\"https:\\\/\\\/wearecapco.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wearecapco.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wearecapco.com\\\/fr\\\/#organization\",\"name\":\"CAP.CO | Creating Adventurous Places Ltd\",\"url\":\"https:\\\/\\\/wearecapco.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wearecapco.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wearecapco.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/cropped-CAP.CO_LOGO_FAVICON.png\",\"contentUrl\":\"https:\\\/\\\/wearecapco.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/cropped-CAP.CO_LOGO_FAVICON.png\",\"width\":512,\"height\":512,\"caption\":\"CAP.CO | Creating Adventurous Places Ltd\"},\"image\":{\"@id\":\"https:\\\/\\\/wearecapco.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wearecapco\",\"https:\\\/\\\/www.instagram.com\\\/we_are_capco\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/we-are-capco\\\/about\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCN0C8R-6BQd6jU-5iB80lcw\\\/videos\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Skymaze r\u00e9imagin\u00e9 | Parc faunique des Cotswold | CAP.CO","description":"Apr\u00e8s plus d\u2019une d\u00e9cennie d\u2019utilisation constante et 4,5 millions de visiteurs, le Skymaze au CWP a \u00e9t\u00e9 r\u00e9imagin\u00e9 et reconstruit pour une nouvelle g\u00e9n\u00e9ration.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wearecapco.com\/fr\/news\/le-skymaze-reimagine\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Skymaze r\u00e9imagin\u00e9 | Parc faunique des Cotswold | CAP.CO","og_description":"Apr\u00e8s plus d\u2019une d\u00e9cennie d\u2019utilisation constante et 4,5 millions de visiteurs, le Skymaze au CWP a \u00e9t\u00e9 r\u00e9imagin\u00e9 et reconstruit pour une nouvelle g\u00e9n\u00e9ration.","og_url":"https:\/\/wearecapco.com\/fr\/news\/le-skymaze-reimagine\/","og_site_name":"CAP.CO | Creating Adventurous Places Ltd.","article_publisher":"https:\/\/www.facebook.com\/wearecapco","og_image":[{"width":1536,"height":1024,"url":"https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Molly-Skymaze-lead-image-Created-by-CAP.CO_.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wearecapco.com\/fr\/news\/le-skymaze-reimagine\/","url":"https:\/\/wearecapco.com\/fr\/news\/le-skymaze-reimagine\/","name":"Le Skymaze r\u00e9imagin\u00e9 | Parc faunique des Cotswold | CAP.CO","isPartOf":{"@id":"https:\/\/wearecapco.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wearecapco.com\/fr\/news\/le-skymaze-reimagine\/#primaryimage"},"image":{"@id":"https:\/\/wearecapco.com\/fr\/news\/le-skymaze-reimagine\/#primaryimage"},"thumbnailUrl":"https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Molly-Skymaze-lead-image-Created-by-CAP.CO_.jpg","datePublished":"2026-04-22T15:37:05+00:00","description":"Apr\u00e8s plus d\u2019une d\u00e9cennie d\u2019utilisation constante et 4,5 millions de visiteurs, le Skymaze au CWP a \u00e9t\u00e9 r\u00e9imagin\u00e9 et reconstruit pour une nouvelle g\u00e9n\u00e9ration.","breadcrumb":{"@id":"https:\/\/wearecapco.com\/fr\/news\/le-skymaze-reimagine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wearecapco.com\/fr\/news\/le-skymaze-reimagine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wearecapco.com\/fr\/news\/le-skymaze-reimagine\/#primaryimage","url":"https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Molly-Skymaze-lead-image-Created-by-CAP.CO_.jpg","contentUrl":"https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Molly-Skymaze-lead-image-Created-by-CAP.CO_.jpg","width":1536,"height":1024,"caption":"Henry and Molly Skymaze lead image - Created by CAP.CO"},{"@type":"BreadcrumbList","@id":"https:\/\/wearecapco.com\/fr\/news\/le-skymaze-reimagine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wearecapco.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Actualit\u00e9s","item":"https:\/\/wearecapco.com\/fr\/news\/"},{"@type":"ListItem","position":3,"name":"Le Skymaze r\u00e9imagin\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/wearecapco.com\/fr\/#website","url":"https:\/\/wearecapco.com\/fr\/","name":"CAP.CO | Creating Adventurous Places Ltd.","description":"Creating adventurous places for every imagination","publisher":{"@id":"https:\/\/wearecapco.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wearecapco.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/wearecapco.com\/fr\/#organization","name":"CAP.CO | Creating Adventurous Places Ltd","url":"https:\/\/wearecapco.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wearecapco.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/wearecapco.com\/wp-content\/uploads\/2025\/09\/cropped-CAP.CO_LOGO_FAVICON.png","contentUrl":"https:\/\/wearecapco.com\/wp-content\/uploads\/2025\/09\/cropped-CAP.CO_LOGO_FAVICON.png","width":512,"height":512,"caption":"CAP.CO | Creating Adventurous Places Ltd"},"image":{"@id":"https:\/\/wearecapco.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wearecapco","https:\/\/www.instagram.com\/we_are_capco\/","https:\/\/www.linkedin.com\/company\/we-are-capco\/about\/","https:\/\/www.youtube.com\/channel\/UCN0C8R-6BQd6jU-5iB80lcw\/videos"]}]}},"main_category":[{"id":31,"name":"Attractions","slug":"attractions-fr","icon":{"ID":15952,"id":15952,"title":"attractions icon","filename":"attractions_1@72x.png","filesize":2544,"url":"https:\/\/wearecapco.com\/wp-content\/uploads\/2019\/05\/attractions_1@72x.png","link":"https:\/\/wearecapco.com\/fr\/attractions_172x-2\/","alt":"","author":"1","description":"attractions icon","caption":"","name":"attractions_172x-2","status":"inherit","uploaded_to":0,"date":"2019-05-01 15:09:18","modified":"2019-05-01 15:09:18","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/wearecapco.com\/wp-includes\/images\/media\/default.png","width":163,"height":163,"sizes":{"thumbnail":"https:\/\/wearecapco.com\/wp-content\/uploads\/2019\/05\/attractions_1@72x-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/wearecapco.com\/wp-content\/uploads\/2019\/05\/attractions_1@72x.png","medium-width":163,"medium-height":163,"medium_large":"https:\/\/wearecapco.com\/wp-content\/uploads\/2019\/05\/attractions_1@72x.png","medium_large-width":163,"medium_large-height":163,"large":"https:\/\/wearecapco.com\/wp-content\/uploads\/2019\/05\/attractions_1@72x.png","large-width":163,"large-height":163,"1536x1536":"https:\/\/wearecapco.com\/wp-content\/uploads\/2019\/05\/attractions_1@72x.png","1536x1536-width":163,"1536x1536-height":163,"2048x2048":"https:\/\/wearecapco.com\/wp-content\/uploads\/2019\/05\/attractions_1@72x.png","2048x2048-width":163,"2048x2048-height":163,"hero-image-x1":"https:\/\/wearecapco.com\/wp-content\/uploads\/2019\/05\/attractions_1@72x.png","hero-image-x1-width":163,"hero-image-x1-height":163,"projects":"https:\/\/wearecapco.com\/wp-content\/uploads\/2019\/05\/attractions_1@72x.png","projects-width":163,"projects-height":163,"post-thumbnail":"https:\/\/wearecapco.com\/wp-content\/uploads\/2019\/05\/attractions_1@72x-125x125.png","post-thumbnail-width":125,"post-thumbnail-height":125}}},{"id":28,"name":"Jeu d'aventure","slug":"jeu-daventure","icon":{"ID":15951,"id":15951,"title":"adventure play icon","filename":"adventure-play_1@72x.png","filesize":2201,"url":"https:\/\/wearecapco.com\/wp-content\/uploads\/2019\/05\/adventure-play_1@72x.png","link":"https:\/\/wearecapco.com\/fr\/adventure-play_172x-2\/","alt":"","author":"1","description":"adventure play icon","caption":"","name":"adventure-play_172x-2","status":"inherit","uploaded_to":0,"date":"2019-05-01 15:09:17","modified":"2019-05-01 15:09:17","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/wearecapco.com\/wp-includes\/images\/media\/default.png","width":163,"height":163,"sizes":{"thumbnail":"https:\/\/wearecapco.com\/wp-content\/uploads\/2019\/05\/adventure-play_1@72x-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/wearecapco.com\/wp-content\/uploads\/2019\/05\/adventure-play_1@72x.png","medium-width":163,"medium-height":163,"medium_large":"https:\/\/wearecapco.com\/wp-content\/uploads\/2019\/05\/adventure-play_1@72x.png","medium_large-width":163,"medium_large-height":163,"large":"https:\/\/wearecapco.com\/wp-content\/uploads\/2019\/05\/adventure-play_1@72x.png","large-width":163,"large-height":163,"1536x1536":"https:\/\/wearecapco.com\/wp-content\/uploads\/2019\/05\/adventure-play_1@72x.png","1536x1536-width":163,"1536x1536-height":163,"2048x2048":"https:\/\/wearecapco.com\/wp-content\/uploads\/2019\/05\/adventure-play_1@72x.png","2048x2048-width":163,"2048x2048-height":163,"hero-image-x1":"https:\/\/wearecapco.com\/wp-content\/uploads\/2019\/05\/adventure-play_1@72x.png","hero-image-x1-width":163,"hero-image-x1-height":163,"projects":"https:\/\/wearecapco.com\/wp-content\/uploads\/2019\/05\/adventure-play_1@72x.png","projects-width":163,"projects-height":163,"post-thumbnail":"https:\/\/wearecapco.com\/wp-content\/uploads\/2019\/05\/adventure-play_1@72x-125x125.png","post-thumbnail-width":125,"post-thumbnail-height":125}}}],"featured_image":"https:\/\/wearecapco.com\/wp-content\/uploads\/2026\/04\/Henry-and-Molly-Skymaze-lead-image-Created-by-CAP.CO_.jpg","_links":{"self":[{"href":"https:\/\/wearecapco.com\/fr\/wp-json\/wp\/v2\/news\/22969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wearecapco.com\/fr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/wearecapco.com\/fr\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wearecapco.com\/fr\/wp-json\/wp\/v2\/media\/22964"}],"wp:attachment":[{"href":"https:\/\/wearecapco.com\/fr\/wp-json\/wp\/v2\/media?parent=22969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wearecapco.com\/fr\/wp-json\/wp\/v2\/categories?post=22969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}